{"id":78,"count":1,"description":"","link":"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/map-basque-country\/","name":"Map of the Basque Country","slug":"map-basque-country","taxonomy":"category","parent":71,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carte du Pays Basque | Les provinces, la culture et le climat du Pays Basque<\/title>\n<meta name=\"description\" content=\"Explorez le Pays Basque en toute simplicit\u00e9 gr\u00e2ce \u00e0 notre carte en ligne. Obtenez des indications claires pour d\u00e9couvrir les endroits embl\u00e9matiques de cette belle r\u00e9gion.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/map-basque-country\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carte du Pays Basque | Les provinces, la culture et le climat du Pays Basque\" \/>\n<meta property=\"og:description\" content=\"Explorez le Pays Basque en toute simplicit\u00e9 gr\u00e2ce \u00e0 notre carte en ligne. Obtenez des indications claires pour d\u00e9couvrir les endroits embl\u00e9matiques de cette belle r\u00e9gion.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/map-basque-country\/\" \/>\n<meta property=\"og:site_name\" content=\"Camping Ametza\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.camping-ametza.com\/wp-content\/uploads\/2023\/11\/danses-basques-camping-ametza.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/map-basque-country\/\",\"url\":\"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/map-basque-country\/\",\"name\":\"Carte du Pays Basque | Les provinces, la culture et le climat du Pays Basque\",\"isPartOf\":{\"@id\":\"https:\/\/www.camping-ametza.com\/en\/#website\"},\"description\":\"Explorez le Pays Basque en toute simplicit\u00e9 gr\u00e2ce \u00e0 notre carte en ligne. Obtenez des indications claires pour d\u00e9couvrir les endroits embl\u00e9matiques de cette belle r\u00e9gion.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/map-basque-country\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/map-basque-country\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Camping Hendaye, au Pays basque\",\"item\":\"https:\/\/www.camping-ametza.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tourism Basque Country\",\"item\":\"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Map of the Basque Country\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.camping-ametza.com\/en\/#website\",\"url\":\"https:\/\/www.camping-ametza.com\/en\/\",\"name\":\"Camping Ametza\",\"description\":\"Ametza, ensemble autrement\",\"publisher\":{\"@id\":\"https:\/\/www.camping-ametza.com\/en\/#organization\"},\"alternateName\":\"Ametza\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.camping-ametza.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.camping-ametza.com\/en\/#organization\",\"name\":\"Camping Ametza\",\"alternateName\":\"Ametza\",\"url\":\"https:\/\/www.camping-ametza.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.camping-ametza.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.camping-ametza.com\/wp-content\/uploads\/2023\/11\/logo-camping-ametza-1.webp\",\"contentUrl\":\"https:\/\/www.camping-ametza.com\/wp-content\/uploads\/2023\/11\/logo-camping-ametza-1.webp\",\"width\":296,\"height\":296,\"caption\":\"Camping Ametza\"},\"image\":{\"@id\":\"https:\/\/www.camping-ametza.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/camping.ametza\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carte du Pays Basque | Les provinces, la culture et le climat du Pays Basque","description":"Explorez le Pays Basque en toute simplicit\u00e9 gr\u00e2ce \u00e0 notre carte en ligne. Obtenez des indications claires pour d\u00e9couvrir les endroits embl\u00e9matiques de cette belle r\u00e9gion.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/map-basque-country\/","og_locale":"en_US","og_type":"article","og_title":"Carte du Pays Basque | Les provinces, la culture et le climat du Pays Basque","og_description":"Explorez le Pays Basque en toute simplicit\u00e9 gr\u00e2ce \u00e0 notre carte en ligne. Obtenez des indications claires pour d\u00e9couvrir les endroits embl\u00e9matiques de cette belle r\u00e9gion.","og_url":"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/map-basque-country\/","og_site_name":"Camping Ametza","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.camping-ametza.com\/wp-content\/uploads\/2023\/11\/danses-basques-camping-ametza.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/map-basque-country\/","url":"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/map-basque-country\/","name":"Carte du Pays Basque | Les provinces, la culture et le climat du Pays Basque","isPartOf":{"@id":"https:\/\/www.camping-ametza.com\/en\/#website"},"description":"Explorez le Pays Basque en toute simplicit\u00e9 gr\u00e2ce \u00e0 notre carte en ligne. Obtenez des indications claires pour d\u00e9couvrir les endroits embl\u00e9matiques de cette belle r\u00e9gion.","breadcrumb":{"@id":"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/map-basque-country\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/map-basque-country\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Camping Hendaye, au Pays basque","item":"https:\/\/www.camping-ametza.com\/en\/"},{"@type":"ListItem","position":2,"name":"Tourism Basque Country","item":"https:\/\/www.camping-ametza.com\/en\/tourism-basque-country\/"},{"@type":"ListItem","position":3,"name":"Map of the Basque Country"}]},{"@type":"WebSite","@id":"https:\/\/www.camping-ametza.com\/en\/#website","url":"https:\/\/www.camping-ametza.com\/en\/","name":"Camping Ametza","description":"Ametza, ensemble autrement","publisher":{"@id":"https:\/\/www.camping-ametza.com\/en\/#organization"},"alternateName":"Ametza","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.camping-ametza.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.camping-ametza.com\/en\/#organization","name":"Camping Ametza","alternateName":"Ametza","url":"https:\/\/www.camping-ametza.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.camping-ametza.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.camping-ametza.com\/wp-content\/uploads\/2023\/11\/logo-camping-ametza-1.webp","contentUrl":"https:\/\/www.camping-ametza.com\/wp-content\/uploads\/2023\/11\/logo-camping-ametza-1.webp","width":296,"height":296,"caption":"Camping Ametza"},"image":{"@id":"https:\/\/www.camping-ametza.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/camping.ametza"]}]}},"_links":{"self":[{"href":"https:\/\/www.camping-ametza.com\/en\/wp-json\/wp\/v2\/categories\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camping-ametza.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.camping-ametza.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.camping-ametza.com\/en\/wp-json\/wp\/v2\/categories\/71"}],"wp:post_type":[{"href":"https:\/\/www.camping-ametza.com\/en\/wp-json\/wp\/v2\/posts?categories=78"},{"href":"https:\/\/www.camping-ametza.com\/en\/wp-json\/wp\/v2\/categorydescription?categories=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}